{"id":122310,"date":"2019-06-17T09:23:23","date_gmt":"2019-06-17T13:23:23","guid":{"rendered":"https:\/\/www.terram.cl\/?p=122310"},"modified":"2019-12-02T13:47:38","modified_gmt":"2019-12-02T16:47:38","slug":"armada-estudia-protocolo-de-eventos-criticos-en-plan-de-descontaminacion","status":"publish","type":"post","link":"https:\/\/www.terram.cl\/carbon\/2019\/06\/armada-estudia-protocolo-de-eventos-criticos-en-plan-de-descontaminacion\/","title":{"rendered":"Armada estudia protocolo de eventos cr\u00edticos en Plan de Descontaminaci\u00f3n"},"content":{"rendered":"<p>A casi tres meses de la puesta en marcha del Plan de Prevenci\u00f3n y Descontaminaci\u00f3n Atmosf\u00e9rica (PDA) para las comunas de Conc\u00f3n, Quintero y Puchuncav\u00ed, que fue aprobado el 31 de marzo de este a\u00f1o, la Armada ejecuta diversas acciones en la bah\u00eda de Quintero para fiscalizar el control de las emisiones contaminantes, principalmente de buques nacionales e internacionales. En este sentido y tal como mandara la nueva herramienta medioambiental en su art\u00edculo 38, la Armada confirm\u00f3 el trabajo de inspecci\u00f3n que realiza a las embarcaciones, lo que est\u00e1 regulado hace a\u00f1os por convenios internacionales y asever\u00f3 que trabajan en un protocolo para episodios cr\u00edticos, acci\u00f3n que dispone el PDA para condiciones adversas de ventilaci\u00f3n.<\/p>\n<p>En este nuevo protocolo, seg\u00fan explic\u00f3 el gobernador mar\u00edtimo de Valpara\u00edso, Juan Gajardo Romero, se aplicar\u00edan medidas de resguardo en la bah\u00eda, en donde se estar\u00eda analizando la posibilidad de suspender los trasvasijes mientras dure la alerta dada por las autoridades sectoriales. \u00abSiendo parte de los organismos del Estado que van a controlar esto, la Armada va a disponer de un protocolo que va a contribuir o ayudar a tener mayor efectividad en el lapso que se decreten los episodios cr\u00edticos, que es lo que interesa. Esto es para contribuir en los episodios cr\u00edticos (&#8230;), algo hay que hacer con el buque porque no est\u00e1 solo, est\u00e1 con una interfaz con la instalaci\u00f3n portuaria y hay que conversar c\u00f3mo va a hacer el protocolo, porque se puede cortar el bombeo (de alg\u00fan combustible) hasta fiscalizar, pero el buque, como tal, est\u00e1 controlado\u00bb, asever\u00f3 Gajardo.<\/p>\n<p>Las personas que participan de la definici\u00f3n del protocolo son personal de nivel local de la autoridad mar\u00edtima, apoyadas por dos direcciones t\u00e9cnicas: la Direcci\u00f3n de Seguridad y Operaciones Mar\u00edtimas (Dirsomar) y la Direcci\u00f3n de intereses Mar\u00edtimos y Medio Ambiente Acu\u00e1tico (Dirinmar). Los cambios a los funcionamientos dentro de la Bah\u00eda de Quintero ante episodios cr\u00edticos est\u00e1n siendo estudiados y se est\u00e1 analizando la mejor opci\u00f3n, en un plazo de 15 d\u00edas, para que el protocolo est\u00e9 terminado.<\/p>\n<p><strong>Suspender trasvasije<\/strong><\/p>\n<p>Dentro de las caracter\u00edsticas de la nueva herramienta de la Armada se est\u00e1 viendo la posibilidad de suspender el trasvasije de combustible de las embarcaciones, lo que har\u00eda directamente la persona encargada de supervisar la descarga y la carga de combustible en la zona, quien se denomina \u00abLoading Master\u00bb .<\/p>\n<p>\u00abPor ejemplo, estamos viendo que se va a actuar sobre la persona que tiene que ver con la transferencia de los productos, cuando est\u00e1n descargando o cargando. Cuando los buques traen productos a los terminales se va a apuntar el protocolo a una acci\u00f3n sobre el Loading Master\u00bb, afirm\u00f3 el gobernador mar\u00edtimo. Si existe un episodio cr\u00edtico, aclar\u00f3 Gajardo, se tomar\u00e1n acciones \u00abdependiendo de qui\u00e9nes est\u00e9n en actividad\u00bb en la Bah\u00eda de Quintero. Precis\u00f3 que existe la posibilidad de que se \u00abpudiera llegar en alg\u00fan momento, en ese lapso (de episodios cr\u00edticos), a no seguir descargando o cargando un combustible como acci\u00f3n contribuyente a la situaci\u00f3n para no emanaci\u00f3n de gases\u00bb.<\/p>\n<p>El episodio cr\u00edtico definido en el Plan de Prevenci\u00f3n y Descontaminaci\u00f3n Atmosf\u00e9rica para Conc\u00f3n, Quintero y Puchuncav\u00ed, seg\u00fan estipula el plan, tiene tres etapas en relaci\u00f3n a la criticidad. \u00c9sta va a definir las acciones a implementar en la bah\u00eda. En definitiva, dijo Gajardo, \u00abtendr\u00e1 que haber un acuerdo. Una vez que se definan ciertos detalles hay que organizarlo con los otros organismo del Estado y aplicar las medidas\u00bb. La posibilidad de cierre de la bah\u00eda, en tanto, fue descartada por Gajardo, quien explic\u00f3 que el ingreso de nuevas embarcaciones ante episodios cr\u00edticos significan un aporte menor respecto a los compuestos: di\u00f3xido de nitr\u00f3geno (NOx) y di\u00f3xido de azufre (S02) Sin embargo, en relaci\u00f3n a los Compuestos Org\u00e1nicos Vol\u00e1tiles (COVs) la autoridad mar\u00edtima precis\u00f3 que \u00abse tiene que ver la situaci\u00f3n referente a qu\u00e9 tipo de operaci\u00f3n est\u00e9 haciendo la embarcaci\u00f3n\u00bb.<\/p>\n<p>Esto, porque \u00abestos compuestos s\u00ed est\u00e1n asociados a las caigas y ah\u00ed se tiene que ver con mayor rigurosidad porque la carga o descarga de hidrocarburos libera ciertos gases. Debe existir una relaci\u00f3n de qu\u00e9 control se est\u00e1 teniendo en tienes y qu\u00e9 control se est\u00e1 teniendo en el mar. Si es a la inversa y el Terminal est\u00e1 enviando combustible, el manejo de esa atm\u00f3sfera es la que el buque tambi\u00e9n tiene. Para eso existen protocolos y manuales que est\u00e1n aprobados\u00bb, recalc\u00f3 Gajardo.<\/p>\n<p><strong>Control y fiscalizaci\u00f3n<\/strong><\/p>\n<p>Desde que entr\u00f3 en vigencia el Plan de Prevenci\u00f3n y Descontaminaci\u00f3n Atmosf\u00e9rica en la zona, la Armada ha realizado 38 inspecciones a naves de bandera extranjera y 12 fiscalizaciones a embarcaciones nacionales que operan en la bah\u00eda. Las fiscalizaciones son parte del control que siempre ha existido, dado el compromiso internacional al Convenio internacional para Prevenir la contaminaci\u00f3n por los buques MARPOL 73\/78. Con el plan, afirm\u00f3 Gajardo, \u00abel cambio es que vino a definir episodios cr\u00edticos y por lo tanto, es ah\u00ed donde nosotros tenemos que lograr una efectividad para que no afecte y no contribuya con efectos de gases a la contaminaci\u00f3n atmosf\u00e9rica de Quintero y eso no lo define la autoridad mar\u00edtima, es el mismo plan que dice que hay una resoluci\u00f3n que emite el intendente en base ala poca ventilaci\u00f3n del momento\u00bb.<\/p>\n<p>En tanto, en relaci\u00f3n al articulo 38 del PDA, se determina que \u00abla Armada controlar\u00e1 las emisiones de los buques en base a lo que estipula el convenio internacional en esta materia. Este convenio (MARPOL) es un libro que tiene una serie de anexos y en el n\u00famero 6 habla de las emisiones de gases de los buques. Los que est\u00e1n referidos a los NOx est\u00e1n controlados en los buques mercantes en viaje internacional y nacional\u00bb, dijo Gajardo. Bajo este sistema de convenio internacional existen los inspectores del Estado Rector del Puerto, que en todos los puertos principales fiscalizan.<\/p>\n<p>Gajardo precis\u00f3 que \u00aba los buques de bandera extranjera se le hacen una sede de inspecciones, se le piden los certificados que acreditan el c\u00f3mo fue construido, cu\u00e1l es su mantenimiento y tambi\u00e9n cu\u00e1l es el control asociado con el S02\u00bb. El di\u00f3xido de azufre \u00abtiene sus diferentes disposiciones, como por ejemplo d\u00f3nde hizo el combustible\u00bb. La Armada, en el plan de descontaminaci\u00f3n, asumi\u00f3 el compromiso de realizar el 100% de fiscalizaciones a las naves nacionales, el 100% de inspecci\u00f3n a naves extranjeras que traigan COVs e incrementar en un 25% las visitas inspectivas.<\/p>\n<p><strong>Varamientos de carb\u00f3n en la bah\u00eda<\/strong><\/p>\n<p>\u2022 Este viernes 14 de junio se cumpli\u00f3 un a\u00f1o de la resoluci\u00f3n del primer sumario de la Armada en torno a los varamientos de carb\u00f3n en la playa de Ventanas, en Puchuncav\u00ed, que apunta como responsable a la empresa Aes Gener. El proceso est\u00e1 en fase final y prontamente habr\u00eda una resoluci\u00f3n. Actualmente, dijo Gajardo, \u00abse contin\u00faa en la etapa probatoria, en la cual el responsable, haciendo uso de su derecho, est\u00e1 buscando los soportes t\u00e9cnicos para demostrar una simulaci\u00f3n que indicar\u00eda que habr\u00edan otras empresas que aportan\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acci\u00f3n se implementar\u00eda en 15 d\u00edas m\u00e1s en la Bah\u00eda de Quintero y busca suspender emisiones contaminantes de buques. Una de las medidas ser\u00eda detener trasvasijes mientras dura alerta. Fuente: El Mercurio de Valpara\u00edso, 17 de junio de 2019. <\/p>\n","protected":false},"author":12,"featured_media":118606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[132,38,133,122],"class_list":["post-122310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resumen-de-prensa","tag-bahia-de-quintero","tag-descarbonizacion","tag-quintero-puchuncavi","tag-zonas-de-sacrificio"],"_links":{"self":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/122310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/comments?post=122310"}],"version-history":[{"count":0,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/122310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media\/118606"}],"wp:attachment":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media?parent=122310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/categories?post=122310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/tags?post=122310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}