{"id":122342,"date":"2019-06-18T10:08:00","date_gmt":"2019-06-18T14:08:00","guid":{"rendered":"https:\/\/www.terram.cl\/?p=122342"},"modified":"2019-12-02T13:47:38","modified_gmt":"2019-12-02T16:47:38","slug":"plan-de-descarbonizacion-poca-claridad-en-la-segunda-parte-del-compromiso","status":"publish","type":"post","link":"https:\/\/www.terram.cl\/carbon\/2019\/06\/plan-de-descarbonizacion-poca-claridad-en-la-segunda-parte-del-compromiso\/","title":{"rendered":"Plan de descarbonizaci\u00f3n: poca claridad en la segunda parte del compromiso"},"content":{"rendered":"<p>Hasta 2025 todo parece ir bien con el plan de descarbonizaci\u00f3n. Y Engie, una de las empresas comprometidas, ya cerr\u00f3 dos de sus plantas en Tocopilla. Sin embargo el plan de cierre de estas ya estaba previsto. As\u00ed, tanto la empresa como el Gobierno ten\u00edan coincidencia de intereses. Pero, \u00bfqu\u00e9 pasar\u00e1 despu\u00e9s de la primera parte del plan de descarbonizaci\u00f3n?<\/p>\n<p>Si bien las empresas se comprometieron a ser parte de este proceso, sus propias condiciones, la marcha de la econom\u00eda, del gobierno y la tecnolog\u00eda al 2040 pueden cambiar.<\/p>\n<p>&#8216;Hay que ser cuidadoso, no creo que sea prudente comprometer fechas. Este compromiso del 2040, veremos, depende de condiciones del sistema, lo \u00fanico claro es que a 2025 se sacan 8 centrales&#8217; coment\u00f3 la gerente general de la consultora Energ\u00e9tica, Mar\u00eda Isabel Gonz\u00e1lez. Y agrega que considera el compromiso &#8216;bastante verde&#8217; y osado.<\/p>\n<p>Las empresas incluso creen que pueden avanzar m\u00e1s r\u00e1pido, pero que depender\u00e1 de las condiciones del minuto. &#8216;Creemos que podremos avanzar m\u00e1s r\u00e1pido pero eso depender\u00e1 del desarrollo de las renovables, la estabilidad del sistema el\u00e9ctrico del pa\u00eds y el desarrollo de l\u00edneas de transmisi\u00f3n&#8217;, afirman desde Enel.<\/p>\n<p>En el lanzamiento del compromiso el Presidente Pi\u00f1era mencion\u00f3 que despu\u00e9s de la primera etapa se realizar\u00e1n estudios cada cinco a\u00f1os para definir el cronograma de salida de las centrales. Algunos lo consideraron poco ambicioso y poco transparente y a otros les pareci\u00f3 dif\u00edcil de hacer cumplir por parte del gobierno de turno.<\/p>\n<p>&#8216;Es completamente viable cerrar las termoel\u00e9ctricas a carb\u00f3n incluso antes del 2040. Lo importante es conocer los detalles de los acuerdos entre las empresas y el Gobierno, as\u00ed como la informaci\u00f3n que usaron para acordar este plazo, pues todo ha sido poco transparente&#8217; dijo la directora ejecutiva de Fundaci\u00f3n Terram, Flavia Liberona.<\/p>\n<p><strong>Mecanismos m\u00e1s efectivos<\/strong><\/p>\n<p>Hasta ahora el plan se trata de compromisos que de hecho las mismas empresas han relativizado. Pues el acuerdo detalla que deber\u00e1n cumplirse una serie de condiciones para habilitar el programa a 2040.<\/p>\n<p>Por ejemplo, en el caso de Colb\u00fan, anunciaron que el cierre de la central Santa Mar\u00eda quedar\u00eda sujeto a no afectar al incumplimiento de contrato que tienen con Codelco, el cual se extiende a 2044. aes gener, por su parte, explic\u00f3 que &#8216;cada cinco a\u00f1os definiremos nuevas metas&#8217;. Finalmente, Engie ha declarado que cualquier modificaci\u00f3n o aprobaci\u00f3n correspondiente tendr\u00e1 que pasar por el directorio o junta de accionistas. Desde la firma dijeron que el directorio ha aprobado lo declarado respecto a sus unidades 14 y 15, que son parte del plan de cierre hasta 2025 y no se refirieron a lo que pasar\u00eda despu\u00e9s de esa fecha.<\/p>\n<p>&#8216;Pueden rechazarlo (el acuerdo). Esas centrales tienen vida \u00fatil por 40 a\u00f1os. Si todav\u00eda pueden funcionar y tienen contrato obviamente van a seguir funcionando&#8217;, agrega Gonz\u00e1lez. Con todo, desde Colb\u00fan declaran que consideran factible cumplir las metas que se comprometieron en el plan gubernamental.<\/p>\n<p>Frente a esto, desde el Ejecutivo plantean que &#8216;todas las empresas deben respetar evidentemente los \u00f3rganos de su gobierno corporativo para la toma de decisiones (&#8230;) No vemos que este elemento propio del gobierno corporativo de las empresas interfiera con los acuerdos&#8217;, explic\u00f3 el secretario ejecutivo de la Comisi\u00f3n Nacional de Energ\u00eda, Jos\u00e9 Venegas.<\/p>\n<p>Desde la academia, surgen otras alternativas que parecen m\u00e1s razonables desde el punto de vista econ\u00f3mico, y que a la vez son m\u00e1s institucionales que un mero compromiso entre un futuro gobierno (que puede tener otras prioridades) y las empresas (que tambi\u00e9n pueden estar enfrentando escenarios distintos al de hoy).<\/p>\n<p>Una de ellas es aumentar impuestos a las emisiones de elementos contaminantes. &#8216;Entre las herramientas (m\u00e1s viables) est\u00e1 el impuesto al CO{-2}, sabemos que actualmente US$ 5 por tonelada es insuficiente, y ya contamos con estudios para proponer y optar por un valor mayor que logre internalizar o reflejar los costos sociales y ambientales que tienen esas emisiones&#8217;, explic\u00f3 el director de WWF, Ricardo Bosshard.<\/p>\n<p>Otra de las ideas que surgen entre los expertos es revisar la legislaci\u00f3n actual de emisiones que tienen las centrales y las reconversiones de estas. &#8216;Por ejemplo, actualizar la norma de emisiones de termoel\u00e9ctricas, proceso que est\u00e1 retrasado. No permitir la reconversi\u00f3n de centrales, que este tipo de centrales no queden en el sistema como unidades de respaldo, son algunas medidas&#8217;, agrega Liberona.<\/p>\n<p>&#8216;Una vez que se usan los impuestos correctos las energ\u00edas m\u00e1s contaminantes son m\u00e1s caras y eso las hace menos competitivas que las energ\u00edas limpias. Eso acelera el cambio a una matriz energ\u00e9tica m\u00e1s limpia&#8217;, plantea el profesor de la Escuela de Gobierno de la UAI Claudio Agostini. Y agrega que &#8216;implentar un impuesto al CO{-2} y subir el impuesto al di\u00e9sel son pol\u00edticas correctas que deber\u00edan implementarse ahora, independiente del acuerdo de descarbonizaci\u00f3n&#8217;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 2025, aparecen los mayores desaf\u00edos y no est\u00e1 claro c\u00f3mo se va a llevar a cabo el plan. Fuente: La Segunda, 17 junio de 2019. <\/p>\n","protected":false},"author":12,"featured_media":119154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[134,135,38],"class_list":["post-122342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resumen-de-prensa","tag-134","tag-135","tag-descarbonizacion"],"_links":{"self":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/122342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/comments?post=122342"}],"version-history":[{"count":0,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/122342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media\/119154"}],"wp:attachment":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media?parent=122342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/categories?post=122342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/tags?post=122342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}