{"id":1282,"date":"2016-08-19T12:41:51","date_gmt":"2016-08-19T12:41:51","guid":{"rendered":"http:\/\/localhost\/terram\/nomascarbon\/\/?p=1282"},"modified":"2016-08-19T12:41:51","modified_gmt":"2016-08-19T12:41:51","slug":"medicos-antofagasta-emplazan-candidatos-brindar-soluciones-alto-indice-cancer","status":"publish","type":"post","link":"https:\/\/www.terram.cl\/carbon\/2016\/08\/medicos-antofagasta-emplazan-candidatos-brindar-soluciones-alto-indice-cancer\/","title":{"rendered":"M\u00e9dicos de Antofagasta emplazan a candidatos a brindar soluciones por alto \u00edndice de c\u00e1ncer"},"content":{"rendered":"<p style=\"text-align: justify\">Mediante una carta p\u00fablica, el Colegio M\u00e9dico de Antofagasta emplaz\u00f3 a los candidatos a alcalde y concejal de la regi\u00f3n a hacerse cargo y dar soluciones a la comunidad frente a los altos \u00edndices de c\u00e1ncer que registran Antofagasta, Tocopilla, Taltal, Mejillones, Sierra Gorda, Calama, San Pedro de Atacama, Mar\u00eda Elena y Ollag\u00fce.<!--more--><\/p>\n<p style=\"text-align: justify\">De acuerdo a los dos \u00faltimos informes de Quinquenio de C\u00e1ncer, quienes obran en poder de la Autoridad Sanitaria y el Ministerio de Salud, la regi\u00f3n de Antofagasta cuenta con la m\u00e1s alta tasa de c\u00e1ncer por habitante del pa\u00eds y el mundo, siendo la principal causa de muerte en las nueve comunas de la regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">En la misiva firmada por el presidente de la organizaci\u00f3n, doctor Aliro Bolados, se indica que atendido este hecho, solicitan a los postulantes sumarse a una gran campa\u00f1a contra el c\u00e1ncer, alejando a las fuentes de contaminaci\u00f3n de los radios urbanos e impulsando un Plan Auge regional que permita dar cobertura al c\u00e1ncer.<\/p>\n<p style=\"text-align: justify\">El llamado tiene como objetivo que los candidatos se comprometan p\u00fablicamente a incorporar una fuerte prevenci\u00f3n del c\u00e1ncer en sus planes y programas de gesti\u00f3n municipal en las \u00e1reas de salud y medio ambiente, tomando en consideraci\u00f3n las cifras de enfermos que presenta la regi\u00f3n, cuya situaci\u00f3n, a juicio del Colegio M\u00e9dico de Chile, guarda relaci\u00f3n con la ingesta hist\u00f3rica de ars\u00e9nico, contaminaci\u00f3n y pasivos ambientales.<\/p>\n<p style=\"text-align: justify\">A continuaci\u00f3n, la carta emanada por el Colegio M\u00e9dico de Antofagasta:<\/p>\n<p style=\"text-align: justify\">Estimados Candidatos a<br \/>\nAlcalde y Concejales de la<br \/>\nRegi\u00f3n de Antofagasta:<\/p>\n<p style=\"text-align: justify\">Como Colegio M\u00e9dico de Chile Regional Antofagasta y basados en la Carta de Derechos y Deberes de los Pacientes y tambi\u00e9n en lo que dice relaci\u00f3n a la responsabilidad p\u00fablica en materia de salud, que deber\u00e1n asumir todas las autoridades municipales, que logren obtener el cargo de alcaldes y concejales de la Regi\u00f3n de Antofagasta, en las pr\u00f3ximas Elecciones Municipales 2016, es nuestro deber informar lo siguiente:<\/p>\n<p style=\"text-align: justify\">1.- Que la Regi\u00f3n de Antofagasta y las comunas de la zona que la integran, de acuerdo a los dos \u00faltimos Informes de Quinquenio de C\u00e1ncer, que obran en poder de la Autoridad Sanitaria y el Ministerio de Salud, cuenta con la m\u00e1s alta tasa de c\u00e1ncer por habitante del pa\u00eds y el mundo, siendo la principal causa de muerte en las nueve comunas de la regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">2.- Que en el detalle, los habitantes de la Regi\u00f3n de Antofagasta y sus descendientes, que bebieron agua potable con ars\u00e9nico, en alt\u00edsimas concentraciones, con un promedio m\u00e1ximo de 860 microgramos de ars\u00e9nico, por cada litro del vital elemento, entre los a\u00f1os 1958 y 1970, cuentan con una mayor susceptibilidad al c\u00e1ncer. Por esta raz\u00f3n, solicitamos a todos los candidatos de la regi\u00f3n, impulsar una fuerte pol\u00edtica de salud y prevenci\u00f3n de esta enfermedad, en todas y cada una de las comunas de la regi\u00f3n, un nulo consumo de tabaco, la generaci\u00f3n intensiva de parques, plazas, \u00e1reas verdes y pavimentaci\u00f3n, adem\u00e1s de actividades deportivas en sectores alejados de toda fuente de contaminaci\u00f3n, pasivos ambientales o zonas de impacto ambiental minero, industrial, portuario y energ\u00e9tico, teniendo en consideraci\u00f3n que todo proyecto de desarrollo, no puede ni debe afectar a los habitantes de nuestras comunas, ya comprometidos en su salud por el hist\u00f3rico drama de la ingesta de ars\u00e9nico en el agua, ya superado con la entrada en operaciones de la desaladora de agua de mar, evitando con ello que sigan aumentando a\u00fan m\u00e1s las cifras de muertes por c\u00e1ncer, cuyos emplazamientos industriales deber\u00e1n desarrollarse en lo posible, fuera del radio urbano de comunas donde habitan ciudadanos susceptibles a esta enfermedad.<\/p>\n<p style=\"text-align: justify\">3.- Que por esta raz\u00f3n, al ser una regi\u00f3n de comunas con habitantes en riesgo permanente por c\u00e1ncer, es deber de las autoridades comunales que resulten elegidas, hacer todos los esfuerzos necesarios para impulsar en conjunto un Plan Auge Regional, que permita dar cobertura GES para todos los habitantes de la regi\u00f3n, a los diversos tipos de c\u00e1ncer que hoy afectan gravemente la salud de la familia regional, y particularmente a los ciudadanos de Antofagasta, Tocopilla, Taltal, Mejillones, Sierra Gorda, Calama, San Pedro de Atacama, Mar\u00eda Elena y Ollag\u00fce. No puede ser posible, que hoy en pleno siglo 21, s\u00f3lo por citar un ejemplo, el c\u00e1ncer de pulm\u00f3n que m\u00e1s mata a los habitantes de la regi\u00f3n, a\u00fan no est\u00e9 incluido en el Plan Auge, condenando no s\u00f3lo a la muerte a miles de personas, sino que tambi\u00e9n a la imposibilidad de cubrir los elevados gastos m\u00e9dicos de esta grave enfermedad, que genera un enorme desastre econ\u00f3mico a la familia regional y una muerte horrenda a quienes sufren sus consecuencias.<\/p>\n<p style=\"text-align: justify\">4.- Asimismo, finalmente creemos que es deber \u00e9tico y moral de las futuras autoridades, que puedan incorporar en sus planes de gesti\u00f3n comunal, salud y medio ambiente, esta informaci\u00f3n, que obra en poder de la autoridad sanitaria y del Colegio M\u00e9dico de Chile Regional Antofagasta, con el fin de unirnos todos en esta &#8216;Campa\u00f1a de Salud contra el C\u00e1ncer de la Regi\u00f3n de Antofagasta&#8217;, cuyo objetivo no es otro que el bienestar y la salud de todos y cada uno de los habitantes de la regi\u00f3n, impulsando un desarrollo saludable y amigable con el medio ambiente, principalmente asegurando un futuro para nuestros hijos, adultos mayores, enfermos cr\u00f3nicos, trabajadores activos y pasivos y principalmente a las v\u00edctimas de esta dram\u00e1tica enfermedad, como es el c\u00e1ncer, quienes hoy tanto nos necesitan.<\/p>\n<p style=\"text-align: justify\">Dr. Aliro Bolados Castillo<br \/>\nPresidente<br \/>\nConsejo Regional Antofagasta<br \/>\nColegio M\u00e9dico de Chile<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante una carta p\u00fablica, el Colegio M\u00e9dico de Antofagasta emplaz\u00f3 a los candidatos a alcalde y concejal de la regi\u00f3n a hacerse cargo y dar soluciones a la comunidad frente a los altos \u00edndices de c\u00e1ncer que registran Antofagasta, Tocopilla, Taltal, Mejillones, Sierra Gorda, Calama, San Pedro de Atacama, Mar\u00eda Elena y Ollag\u00fce.<\/p>\n","protected":false},"author":16,"featured_media":125008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"class_list":["post-1282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resumen-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/comments?post=1282"}],"version-history":[{"count":0,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media\/125008"}],"wp:attachment":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media?parent=1282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/categories?post=1282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/tags?post=1282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}