{"id":1659,"date":"2018-01-29T11:30:35","date_gmt":"2018-01-29T15:30:35","guid":{"rendered":"http:\/\/localhost\/terram\/nomascarbon\/\/?p=1659"},"modified":"2018-01-29T11:30:35","modified_gmt":"2018-01-29T15:30:35","slug":"puerto-ventanas-registro-131-varamientos-carbon-ano-pasado","status":"publish","type":"post","link":"https:\/\/www.terram.cl\/carbon\/2018\/01\/puerto-ventanas-registro-131-varamientos-carbon-ano-pasado\/","title":{"rendered":"Puerto Ventanas registr\u00f3 131 varamientos de carb\u00f3n durante el a\u00f1o pasado"},"content":{"rendered":"<p>Un total de 34 toneladas de carb\u00f3n recuperaron operativos de limpieza dispuestos por la autoridad mar\u00edtima ante 147 episodios de varamiento de este combustible ocurridos en las playas de Puerto Ventanas, en la V Regi\u00f3n, entre noviembre de 2016 y diciembre de 2017. El a\u00f1o pasado registr\u00f3 131 episodios.<br \/>\nLos datos fueron entregados v\u00eda Ley de Transparencia por la Armada al ambientalista Hern\u00e1n Ram\u00edrez. Pese a la fiscalizaci\u00f3n realizada a la descarga de carb\u00f3n en el puerto, la autoridad no ha podido establecer el origen de esta contaminaci\u00f3n.<br \/>\nFuente: El Mercurio.<br \/>\n<a href=\"http:\/\/localhost\/terram\/nomascarbon\/\/2017\/11\/varamientos-carbon-ventanas-una-situacion-abandono\/\">Lee columna \u00abVaramientos de carb\u00f3n en Ventanas: una situaci\u00f3n de abandono\u00bb de Hern\u00e1n Ram\u00edrez aqu\u00ed.\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un total de 34 toneladas de carb\u00f3n recuperaron operativos de limpieza dispuestos por la autoridad mar\u00edtima ante 147 episodios de varamiento de este combustible ocurridos en&#8230;<\/p>\n","protected":false},"author":12,"featured_media":1661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[117,118],"class_list":["post-1659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resumen-de-prensa","tag-varamientos","tag-ventanas"],"_links":{"self":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/comments?post=1659"}],"version-history":[{"count":0,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media\/1661"}],"wp:attachment":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media?parent=1659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/categories?post=1659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/tags?post=1659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}