{"id":1673,"date":"2018-03-19T15:16:30","date_gmt":"2018-03-19T19:16:30","guid":{"rendered":"http:\/\/localhost\/terram\/nomascarbon\/\/?p=1673"},"modified":"2018-03-19T15:16:30","modified_gmt":"2018-03-19T19:16:30","slug":"espana-psoe-pide-al-gobierno-programa-zonas-afectadas-transicion-energetica","status":"publish","type":"post","link":"https:\/\/www.terram.cl\/carbon\/2018\/03\/espana-psoe-pide-al-gobierno-programa-zonas-afectadas-transicion-energetica\/","title":{"rendered":"Espa\u00f1a: PSOE pide al Gobierno programa para zonas afectadas por transici\u00f3n energ\u00e9tica"},"content":{"rendered":"<p>El grupo socialista ha registrado hoy en el Congreso una proposici\u00f3n no de ley en la que insta al Gobierno a aprobar un programa decenal de actuaciones para la transici\u00f3n energ\u00e9tica en territorios especialmente vulnerables por el peso significativo que tiene en ellos el carb\u00f3n y la generaci\u00f3n nuclear.<br \/>\nLa iniciativa se\u00f1ala que los territorios especialmente vulnerables vendr\u00e1n definidos por el peso en los mismos de actividades asociadas a la extracci\u00f3n y al uso del carb\u00f3n, as\u00ed como a la generaci\u00f3n de energ\u00eda nuclear.<br \/>\nEl programa de actuaciones para esas zonas fijar\u00e1 objetivos, plazos y recursos, y quedar\u00e1 sometido a una evaluaci\u00f3n anual de su cumplimiento en el Congreso de los Diputados.<br \/>\nEl objetivo del programa ser\u00e1 anticiparse a los efectos no deseados que pueda tener la transici\u00f3n energ\u00e9tica en el empleo y la actividad econ\u00f3mica de esos territorios.<br \/>\nPara ello, el Gobierno dise\u00f1ar\u00e1 pol\u00edticas activas de empleo id\u00f3neas para favorecer una transici\u00f3n energ\u00e9tica justa, con compromisos presupuestarios de inversi\u00f3n p\u00fablica de la Administraci\u00f3n General del Estado y mecanismos de cooperaci\u00f3n con las correspondientes comunidades aut\u00f3nomas.<br \/>\nEl programa establecer\u00e1 incentivos fiscales para favorecer la inversi\u00f3n privada en esos territorios y crear\u00e1 la figura de las agencias regionales para dinamizar la transici\u00f3n energ\u00e9tica justa, en l\u00ednea con las que ya existen en Reino Unido, Alemania y Francia.<br \/>\nAdem\u00e1s, el programa tendr\u00e1 medidas espec\u00edficas para el apoyo a la investigaci\u00f3n, el desarrollo y la innovaci\u00f3n -incluida la reactivaci\u00f3n de proyectos de almacenamiento y captura de CO2-, el empleo, la formaci\u00f3n, la recuperaci\u00f3n y promoci\u00f3n de iniciativas empresariales, la regeneraci\u00f3n de los territorios afectados, la restauraci\u00f3n medioambiental y el uso alternativo de los emplazamientos.<br \/>\nEl PSOE tambi\u00e9n insta al Gobierno a cumplir en su totalidad el Marco de Actuaci\u00f3n para la Miner\u00eda del Carb\u00f3n y las Comarcas Mineras para el per\u00edodo 2013-2018, cuya vulneraci\u00f3n por parte del Ejecutivo ha sido denunciada por los otros firmantes.<br \/>\nAdem\u00e1s, la proposici\u00f3n pide al Gobierno que defina el papel del carb\u00f3n aut\u00f3ctono como reserva estrat\u00e9gica, que se incorpore a todas las iniciativas europeas e internacionales para promover la transici\u00f3n energ\u00e9tica justa de territorios vulnerables, que cree una unidad especializada que garantice el m\u00e1ximo acceso a fondos comunitarios y del Banco Europeo de Inversiones (BEI) y disponga incentivos para acelerar la concreci\u00f3n de las actuaciones.<br \/>\nLa propuesta del PSOE se produce despu\u00e9s de que el ministro de Energ\u00eda, \u00c1lvaro Nadal, anunciara que el grupo popular presentar\u00eda una proposici\u00f3n de ley para ampliar los motivos por los que puede denegar el cierre de centrales el\u00e9ctricas, despu\u00e9s de haber intentado introducir los cambios a trav\u00e9s de un real decreto, f\u00f3rmula que fue cuestionada en el informe que sobre la norma hizo la Comisi\u00f3n Nacional de los Mercados y la Competencia (CNMC).<br \/>\nFuente: Finanzas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo socialista ha registrado hoy en el Congreso una proposici\u00f3n no de ley en la que insta al Gobierno a aprobar un programa decenal de&#8230;<\/p>\n","protected":false},"author":12,"featured_media":1674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[49,93,113,115],"class_list":["post-1673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resumen-de-prensa","tag-espana","tag-psoe","tag-transicion-energetica","tag-union-europea"],"_links":{"self":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/comments?post=1673"}],"version-history":[{"count":0,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media\/1674"}],"wp:attachment":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media?parent=1673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/categories?post=1673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/tags?post=1673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}