{"id":1761,"date":"2018-05-15T18:06:04","date_gmt":"2018-05-15T22:06:04","guid":{"rendered":"http:\/\/localhost\/terram\/nomascarbon\/\/?p=1761"},"modified":"2018-05-15T18:06:04","modified_gmt":"2018-05-15T22:06:04","slug":"alcalde-coronel-exige-ley-especial-coronel-contaminacion-pesados","status":"publish","type":"post","link":"https:\/\/www.terram.cl\/carbon\/2018\/05\/alcalde-coronel-exige-ley-especial-coronel-contaminacion-pesados\/","title":{"rendered":"Alcalde de Coronel exige ley especial para hacer seguimiento cl\u00ednico a personas afectadas con metales pesados"},"content":{"rendered":"<p><em>El alcalde de Coronel, Boris Chamorro, expuso ante la Comisi\u00f3n de Salud del Congreso, para exigir una ley que garantice un seguimiento cl\u00ednico de las personas contaminadas con metales pesados en la comuna.<\/em><br \/>\nAnte varios senadores y el propio ministro de Salud, Emilio Santelices, el jefe comunal dio a conocer la cr\u00edtica situaci\u00f3n que se vive en su comuna con ni\u00f1os y adultos mayores, expuestos a metales pesados.<br \/>\nChamorro afirm\u00f3 que actualmente a los ni\u00f1os s\u00f3lo se les ha elaborado una ficha cl\u00ednica, pero no han sido sometidos a ex\u00e1menes, es por ello que buscan llegar a los parlamentarios y se legisle al respecto.<br \/>\nUtiliza las teclas de flecha arriba\/abajo para aumentar o disminuir el volumen.<br \/>\nAsimismo indic\u00f3 que tambi\u00e9n es importante obtener la documentaci\u00f3n favorable del Ministerio de Salud, para cerrar el vertedero que se encuentra en el per\u00edmetro de la ciudad y as\u00ed revertir la explosiva aparici\u00f3n de industrias en la zona.<br \/>\nEl alcalde anunci\u00f3 que este 7 de junio el ministro de Salud comprometi\u00f3 su visita a Coronel, con lo que busca interiorizarse en terreno de la situaci\u00f3n que est\u00e1 ocurriendo en la comuna.<br \/>\nFuente: Biobio Chile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alcalde de Coronel, Boris Chamorro, expuso ante la Comisi\u00f3n de Salud del Congreso, para exigir una ley que garantice un seguimiento cl\u00ednico de las personas&#8230;<\/p>\n","protected":false},"author":12,"featured_media":1762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[20,33,37],"class_list":["post-1761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resumen-de-prensa","tag-boris-chamorro","tag-contaminacion-carbon","tag-coronel"],"_links":{"self":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/comments?post=1761"}],"version-history":[{"count":0,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/posts\/1761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media\/1762"}],"wp:attachment":[{"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/media?parent=1761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/categories?post=1761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.terram.cl\/carbon\/wp-json\/wp\/v2\/tags?post=1761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}